{"id":64739,"date":"2026-07-17T00:17:01","date_gmt":"2026-07-17T07:17:01","guid":{"rendered":"https:\/\/bissafety.ca\/?p=64739"},"modified":"2026-07-28T07:32:12","modified_gmt":"2026-07-28T14:32:12","slug":"graham-jackson-wants-you-to-lose-your-ego","status":"publish","type":"post","link":"https:\/\/bissafety.ca\/fr\/graham-jackson-wants-you-to-lose-your-ego\/","title":{"rendered":"Graham Jackson veut que vous laissiez votre ego de c\u00f4t\u00e9\u00a0"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"64739\" class=\"elementor elementor-64739\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-faf2082 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"faf2082\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8dfe9d6\" data-id=\"8dfe9d6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cf4aa3 elementor-icon-list--layout-inline cust-post-breadcrumb elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7cf4aa3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bissafety.ca\/fr\/?page_id=25\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Accueil<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bissafety.ca\/fr\/company-spotlights\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pr\u00e9sentations d'entreprises<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Graham Jackson veut que vous laissiez votre ego de c\u00f4t\u00e9\u00a0<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e718f21 elementor-widget elementor-widget-heading\" data-id=\"e718f21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Graham Jackson veut que vous laissiez votre ego de c\u00f4t\u00e9 <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64077c3 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"64077c3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-da99491 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"da99491\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-914dca5 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"914dca5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38ac278 elementor-share-buttons--shape-rounded elementor-share-buttons--view-icon-text elementor-share-buttons--skin-gradient elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"38ac278\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Share on facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tFacebook\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Share on linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tLinkedIn\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47d06cb elementor-widget elementor-widget-spacer\" data-id=\"47d06cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94b1571 elementor-widget elementor-widget-spacer\" data-id=\"94b1571\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f4ce59d elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"f4ce59d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fcb8899\" data-id=\"fcb8899\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46db2f8 elementor-widget elementor-widget-image\" data-id=\"46db2f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1067\" src=\"https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/Spotlights_QuoteBanner_Graham-scaled.webp\" class=\"attachment-full size-full wp-image-64741\" alt=\"Graham Jackson standing a foot left\" srcset=\"https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/Spotlights_QuoteBanner_Graham-scaled.webp 2560w, https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/Spotlights_QuoteBanner_Graham-300x125.webp 300w, https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/Spotlights_QuoteBanner_Graham-1024x427.webp 1024w, https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/Spotlights_QuoteBanner_Graham-768x320.webp 768w, https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/Spotlights_QuoteBanner_Graham-1536x640.webp 1536w, https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/Spotlights_QuoteBanner_Graham-2048x853.webp 2048w, https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/Spotlights_QuoteBanner_Graham-18x7.webp 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-58365a2 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"58365a2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-19a8e67 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"19a8e67\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-adc2fe1 elementor-widget elementor-widget-text-editor\" data-id=\"adc2fe1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em><span class=\"TextRun SCXW255180779 BCX0\" lang=\"EN-CA\" xml:lang=\"EN-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW255180779 BCX0\">Une blessure qui a failli lui co\u00fbter la vie a appris au directeur de la sant\u00e9 et de la s\u00e9curit\u00e9 de SkyFire Energy \u00e0 faire confiance \u00e0 ses \u00e9quipes plut\u00f4t qu'\u00e0 son r\u00e8glement.<\/span><\/span><\/em><\/p><p><span class=\"TextRun SCXW152085865 BCX0\" lang=\"EN-CA\" xml:lang=\"EN-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW152085865 BCX0\">\u00ab Je ne vous dis pas de faire \u00e7a parce que mon livre dit qu'il faut le faire de cette fa\u00e7on, <a href=\"https:\/\/www.linkedin.com\/in\/graham-jackson-24259b194\/\">Graham Jackson<\/a> dit. C'est parce que je veux que vous rentriez chez vous sains et saufs \u00e0 la fin de la journ\u00e9e. \u00bb<\/span><\/span><span class=\"EOP Selected SCXW152085865 BCX0\" data-ccp-props=\"{}\">\u00a0<\/span><\/p><p><span class=\"TextRun SCXW211622428 BCX0\" lang=\"EN-CA\" xml:lang=\"EN-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW211622428 BCX0\">Graham Jackson est directeur de la sant\u00e9 et de la s\u00e9curit\u00e9 chez SkyFire Energy, l'un des plus importants entrepreneurs en \u00e9nergie solaire de l'Ouest canadien. L'entreprise, d\u00e9tenue par ses employ\u00e9s, installe des syst\u00e8mes solaires partout dans l'Ouest depuis 2001. Comme bien des bons professionnels de la s\u00e9curit\u00e9, il est issu des m\u00e9tiers, pas d'une salle de classe. <b>Il a grandi sur une ferme du sud de l'Alberta, a fait du rod\u00e9o et a fait ses d\u00e9buts en charpenterie \u00e0 seize ans, fabriquant des cl\u00f4tures sur mesure tout en travaillant \u00e0 l'obtention de sa carte de comp\u00e9tence.<\/b> Il est aussi \u00e9tonnamment ouvert au sujet de ce qui l'a men\u00e9 vers la s\u00e9curit\u00e9, et c'est un choix de sa part. \u00ab Je suis fier de mon histoire, dit-il. Ce n'est pas quelque chose dont j'ai honte. \u00bb <\/span><\/span><span class=\"EOP Selected SCXW211622428 BCX0\" data-ccp-props=\"{}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17fb40f e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"17fb40f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0aabf73 elementor-widget elementor-widget-heading\" data-id=\"0aabf73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 id='the-accident'  class=\"elementor-heading-title elementor-size-default\">L'accident<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64e35b1 elementor-widget elementor-widget-text-editor\" data-id=\"64e35b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW184639718 BCX0\" lang=\"EN-CA\" xml:lang=\"EN-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW184639718 BCX0\">En 2014, Graham Jackson \u00e9tait charg\u00e9 de projet pour une entreprise de d\u00e9molition. L'op\u00e9rateur s'\u00e9tait d\u00e9clar\u00e9 malade, alors il a pris la rel\u00e8ve pour garder le chantier en marche, d\u00e9coupant des portes d'acc\u00e8s dans une cage d'ascenseur et hissant des blocs de b\u00e9ton \u00e0 l'aide d'un ancrage de 2 600 livres fix\u00e9 au toit. L'ancrage s'est cisaill\u00e9 en deux. Le b\u00e9ton lui est tomb\u00e9 dessus dans une cage d'escalier, o\u00f9 il n'y avait nulle part o\u00f9 se d\u00e9placer, et lui a coinc\u00e9 le bras.<\/span><\/span><span class=\"EOP Selected SCXW184639718 BCX0\" data-ccp-props=\"{}\">\u00a0<\/span><\/p><p><span class=\"TextRun SCXW8876271 BCX0\" lang=\"EN-CA\" xml:lang=\"EN-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW8876271 BCX0\">Il a perdu environ 75 pour cent de l'usage de son bras droit. Les dommages \u00e9taient internes : une d\u00e9chirure compl\u00e8te de ce que son chirurgien appelait \u00ab la bo\u00eete noire \u00bb du poignet, cens\u00e9e \u00eatre indestructible et, une fois ab\u00eem\u00e9e, irr\u00e9parable. Ce qui a suivi a \u00e9t\u00e9, \u00e0 certains \u00e9gards, plus difficile que la blessure elle-m\u00eame : pr\u00e8s de trois ans sans salaire, treize appels avant que sa r\u00e9clamation soit reconnue et une relation qui a vol\u00e9 en \u00e9clats sous la pression. Au terme de ce combat, il a failli mettre fin \u00e0 ses jours. Ce qui l'a ramen\u00e9, au tout dernier moment, c'est son jeune fils qui criait son nom. Il appelle le gar\u00e7on son petit ange et dit que son fils ignore encore qu'il a sauv\u00e9 la vie de son p\u00e8re. Il a pass\u00e9 des ann\u00e9es en th\u00e9rapie depuis, et il raconte tout cela aujourd'hui, d\u00e9lib\u00e9r\u00e9ment, parce qu'il a vu \u00e0 quelle vitesse une blessure au travail peut entra\u00eener une personne vers le fond. C'est le moteur de tout le reste de ce qu'il fait. \u00ab Parce que moi, j'ai failli ne pas y arriver \u00bb : c'est ainsi qu'il a tendance \u00e0 terminer toute phrase sur les raisons pour lesquelles il tient tant \u00e0 cela.<\/span><\/span><span class=\"EOP Selected SCXW8876271 BCX0\" data-ccp-props=\"{}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-560c2e8 elementor-widget elementor-widget-image\" data-id=\"560c2e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"812\" src=\"https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/GrahamJackson_Worker.webp\" class=\"attachment-full size-full wp-image-64744\" alt=\"Graham Jackson\" srcset=\"https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/GrahamJackson_Worker.webp 1920w, https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/GrahamJackson_Worker-300x127.webp 300w, https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/GrahamJackson_Worker-1024x433.webp 1024w, https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/GrahamJackson_Worker-768x325.webp 768w, https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/GrahamJackson_Worker-1536x650.webp 1536w, https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/GrahamJackson_Worker-18x8.webp 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0c81863 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"0c81863\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d6ffa26 elementor-widget elementor-widget-heading\" data-id=\"d6ffa26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 id='boots-on-the-ground'  class=\"elementor-heading-title elementor-size-default\">Sur le terrain<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5883650 elementor-widget elementor-widget-text-editor\" data-id=\"5883650\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW253876658 BCX0\" lang=\"EN-CA\" xml:lang=\"EN-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW253876658 BCX0\">Le d\u00e9tail que Graham Jackson ne laisse jamais une \u00e9quipe oublier, c'est que son accident n'\u00e9tait pas un accident insolite. \u00ab Ce n'\u00e9tait pas quelque chose d'inhabituel. Ce n'\u00e9tait pas quelque chose de dangereux \u00bb, dit-il. Il travaillait dans le respect des r\u00e8gles, ex\u00e9cutant une t\u00e2che courante, un jour ordinaire. \u00ab Si je m'\u00e9tais tenu \u00e0 un pied vers la gauche, je serais mort. \u00bb<\/span><\/span><span class=\"EOP Selected SCXW253876658 BCX0\" data-ccp-props=\"{}\">\u00a0<\/span><\/p><p><span class=\"TextRun SCXW146512429 BCX0\" lang=\"EN-CA\" xml:lang=\"EN-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW146512429 BCX0\">C'est pourquoi il passe ses journ\u00e9es sur le chantier plut\u00f4t que derri\u00e8re un bureau. Avec une douzaine d'\u00e9quipes d\u00e9ploy\u00e9es un jour donn\u00e9, travaillant sous tension et en hauteur, il essaie de poser les yeux sur presque toutes, \u00e0 l'aff\u00fbt des petites choses que l'exp\u00e9rience rend invisibles. Il affirme sans d\u00e9tour que la comp\u00e9tence ne prot\u00e8ge pas contre le rel\u00e2chement. Il voit \u00ab des personnes hautement qualifi\u00e9es qui deviennent complaisantes \u00bb, et lorsqu'il signale quelque chose, la r\u00e9action qu'il obtient le plus souvent est un merci discret et l'aveu qu'elles-m\u00eames avaient cess\u00e9 de le remarquer.<\/span><\/span><span class=\"EOP SCXW146512429 BCX0\" data-ccp-props=\"{}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a12b883 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"a12b883\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25b5775 elementor-widget elementor-widget-heading\" data-id=\"25b5775\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 id='honey-not-vinegar'  class=\"elementor-heading-title elementor-size-default\">Du miel, pas du vinaigre<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-667a33c elementor-widget elementor-widget-text-editor\" data-id=\"667a33c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW138572179 BCX0\" lang=\"EN-CA\" xml:lang=\"EN-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW138572179 BCX0\">La mission plus large de Graham Jackson est de faire dispara\u00eetre un st\u00e9r\u00e9otype. \u00ab Les professionnels de la s\u00e9curit\u00e9 sont g\u00e9n\u00e9ralement d\u00e9test\u00e9s, dit-il, et je veux me d\u00e9faire de ce pr\u00e9jug\u00e9 voulant qu'on soit l\u00e0 pour vous prendre en faute. \u00bb Il estime que le domaine a m\u00e9rit\u00e9 une partie de cette r\u00e9putation en misant sur l'autorit\u00e9 plut\u00f4t que sur la confiance, et sa solution n'est pas compliqu\u00e9e. \u00ab On attrape plus de mouches avec du miel qu'avec du vinaigre. \u00bb Il a un jour d\u00e9battu pendant trois heures avec un professeur d'universit\u00e9 pour savoir si un responsable de la s\u00e9curit\u00e9 peut \u00eatre ami avec les travailleurs. Il croit toujours qu'il avait raison. Les r\u00e8gles ne plient pas, mais le ton, lui, peut plier. Oui, \u00e7a doit se faire de cette fa\u00e7on, \u00ab mais pas sur un ton mena\u00e7ant \u00bb. Quand les \u00e9quipes ont la conviction qu'il travaille dans leur int\u00e9r\u00eat plut\u00f4t que pour son cartable, elles cessent de redouter son arriv\u00e9e sur le chantier et se mettent \u00e0 l'accueillir.<\/span><\/span><span class=\"EOP SCXW138572179 BCX0\" data-ccp-props=\"{}\">\u00a0<\/span><\/p><p><span class=\"TextRun SCXW232097931 BCX0\" lang=\"EN-CA\" xml:lang=\"EN-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW232097931 BCX0\">La preuve dont il est le plus fier n'est pas un chiffre. SkyFire avait d\u00e9j\u00e0 les bons syst\u00e8mes de s\u00e9curit\u00e9 en place, dit-il, et le travail a consist\u00e9 \u00e0 leur donner vie par le leadership, la constance et la mobilisation des employ\u00e9s. Ce qui a chang\u00e9, c'est la culture. Aujourd'hui, il r\u00e8gne \u00ab un solide climat de confiance et de collaboration \u00bb avec le service de la sant\u00e9 et de la s\u00e9curit\u00e9, et la s\u00e9curit\u00e9 est reconnue comme partie int\u00e9grante de la fa\u00e7on dont l'entreprise fonctionne.<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4af6f91 elementor-widget elementor-widget-image\" data-id=\"4af6f91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"820\" src=\"https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/GrahamJackson_CowboyHat.webp\" class=\"attachment-full size-full wp-image-64743\" alt=\"Graham Jackson\" srcset=\"https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/GrahamJackson_CowboyHat.webp 1920w, https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/GrahamJackson_CowboyHat-300x128.webp 300w, https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/GrahamJackson_CowboyHat-1024x437.webp 1024w, https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/GrahamJackson_CowboyHat-768x328.webp 768w, https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/GrahamJackson_CowboyHat-1536x656.webp 1536w, https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/GrahamJackson_CowboyHat-18x8.webp 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-084b2ad e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"084b2ad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d1fdfe elementor-widget elementor-widget-heading\" data-id=\"4d1fdfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 id='lose-your-ego'  class=\"elementor-heading-title elementor-size-default\">Laissez votre ego de c\u00f4t\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee81b86 elementor-widget elementor-widget-text-editor\" data-id=\"ee81b86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW189777243 BCX0\" lang=\"EN-CA\" xml:lang=\"EN-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW189777243 BCX0\">Demandez \u00e0 Graham Jackson ce qu'il dirait \u00e0 son jeune lui, et la r\u00e9ponse vient sans h\u00e9siter : \u00ab Laisse ton ego de c\u00f4t\u00e9. \u00bb Il voit des gens sortir de l'\u00e9cole convaincus d'en savoir plus que les \u00e9quipes qu'ils sont l\u00e0 pour prot\u00e9ger, et il \u00e9tait l'un d'eux. Il a obtenu son dipl\u00f4me avec distinction, et il lui a quand m\u00eame fallu ravaler son ego pour constater \u00e0 quel point il en savait peu. Les gens sur le terrain, comme il le dit, sont les v\u00e9ritables experts du produit. \u00ab Ils savent tout ce qu'il y a \u00e0 savoir sur ce qu'ils font. \u00bb Apprendre \u00e0 \u00e9couter, \u00e0 demander plut\u00f4t qu'\u00e0 dicter, a \u00e9t\u00e9 la chose la plus difficile qu'il ait eu \u00e0 faire dans cette carri\u00e8re.<\/span><\/span><span class=\"EOP Selected SCXW189777243 BCX0\" data-ccp-props=\"{}\">\u00a0<\/span><\/p><p><span class=\"TextRun SCXW70699374 BCX0\" lang=\"EN-CA\" xml:lang=\"EN-CA\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW70699374 BCX0\">Graham Jackson ne m\u00e8ne pas avec le r\u00e8glement, parce qu'un r\u00e8glement ne l'a pas sauv\u00e9 et qu'il ne sauvera pas la personne devant lui. Ce qui pourrait la sauver, c'est un directeur de la sant\u00e9 et de la s\u00e9curit\u00e9 qui s'est lui-m\u00eame retrouv\u00e9 sous le b\u00e9ton et qui sait exactement ce que co\u00fbte un pied dans la mauvaise direction, un homme qui a d\u00e9cid\u00e9 que le m\u00e9tier n'est pas fait pour \u00eatre ob\u00e9i, mais pour inspirer confiance.<\/span><\/span><span class=\"EOP Selected SCXW70699374 BCX0\" data-ccp-props=\"{}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Graham Jackson est directeur de la sant\u00e9 et de la s\u00e9curit\u00e9 chez SkyFire Energy, l'un des plus importants entrepreneurs en \u00e9nergie solaire de l'Ouest canadien. L'entreprise, d\u00e9tenue par ses employ\u00e9s, installe des syst\u00e8mes solaires partout dans l'Ouest depuis 2001. Comme bien des bons professionnels de la s\u00e9curit\u00e9, il est issu des m\u00e9tiers, pas d'une salle de classe. <\/p>","protected":false},"author":35,"featured_media":64742,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[51],"tags":[937,365,28,934,936,25,722,35,31,32,420,933,935,938,11],"class_list":["post-64739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spotlight-article","tag-alberta","tag-construction-safety","tag-employee-safety","tag-graham-jackson","tag-health-and-safety-manager","tag-leadership","tag-occupational-health-and-safety","tag-risk-management","tag-safety-culture","tag-safety-leadership","tag-safety-professionals","tag-skyfire-energy","tag-solar-industry","tag-workplace-injury","tag-workplace-safety"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Graham Jackson on Safety Leadership and Losing Your Ego<\/title>\n<meta name=\"description\" content=\"From workplace injury to safety leadership, Graham Jackson transformed SkyFire Energy&#039;s safety culture with trust, humility, and experience.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bissafety.ca\/fr\/graham-jackson-wants-you-to-lose-your-ego\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Graham Jackson Wants You to Lose Your Ego\u00a0\" \/>\n<meta property=\"og:description\" content=\"From workplace injury to safety leadership, Graham Jackson transformed SkyFire Energy&#039;s safety culture with trust, humility, and experience.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bissafety.ca\/fr\/graham-jackson-wants-you-to-lose-your-ego\/\" \/>\n<meta property=\"og:site_name\" content=\"BIS Safety Software Canada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BIS.Safety.Software\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-17T07:17:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-28T14:32:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/Spotlights_PreviewCards_Graham.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"721\" \/>\n\t<meta property=\"og:image:height\" content=\"458\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Nishant\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@BISTraining\" \/>\n<meta name=\"twitter:site\" content=\"@BISTraining\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nishant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/graham-jackson-wants-you-to-lose-your-ego\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/graham-jackson-wants-you-to-lose-your-ego\\\/\"},\"author\":{\"name\":\"Nishant\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#\\\/schema\\\/person\\\/458bd937cef8ad403bf31aea9501f264\"},\"headline\":\"Graham Jackson Wants You to Lose Your Ego\u00a0\",\"datePublished\":\"2026-07-17T07:17:01+00:00\",\"dateModified\":\"2026-07-28T14:32:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/graham-jackson-wants-you-to-lose-your-ego\\\/\"},\"wordCount\":982,\"publisher\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/graham-jackson-wants-you-to-lose-your-ego\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bissafety.ca\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Spotlights_PreviewCards_Graham.webp\",\"keywords\":[\"Alberta\",\"construction safety\",\"employee safety\",\"Graham Jackson\",\"Health and Safety Manager\",\"Leadership\",\"Occupational Health and Safety\",\"risk management\",\"safety culture\",\"safety leadership\",\"safety professionals\",\"SkyFire Energy\",\"Solar Industry\",\"Workplace Injury\",\"Workplace safety\"],\"articleSection\":[\"Spotlight Article\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/graham-jackson-wants-you-to-lose-your-ego\\\/\",\"url\":\"https:\\\/\\\/bissafety.ca\\\/graham-jackson-wants-you-to-lose-your-ego\\\/\",\"name\":\"Graham Jackson on Safety Leadership and Losing Your Ego\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/graham-jackson-wants-you-to-lose-your-ego\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/graham-jackson-wants-you-to-lose-your-ego\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bissafety.ca\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Spotlights_PreviewCards_Graham.webp\",\"datePublished\":\"2026-07-17T07:17:01+00:00\",\"dateModified\":\"2026-07-28T14:32:12+00:00\",\"description\":\"From workplace injury to safety leadership, Graham Jackson transformed SkyFire Energy's safety culture with trust, humility, and experience.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/graham-jackson-wants-you-to-lose-your-ego\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bissafety.ca\\\/graham-jackson-wants-you-to-lose-your-ego\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/graham-jackson-wants-you-to-lose-your-ego\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bissafety.ca\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Spotlights_PreviewCards_Graham.webp\",\"contentUrl\":\"https:\\\/\\\/bissafety.ca\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Spotlights_PreviewCards_Graham.webp\",\"width\":721,\"height\":458,\"caption\":\"Graham Jackson\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/graham-jackson-wants-you-to-lose-your-ego\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bissafety.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Graham Jackson Wants You to Lose Your Ego\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#website\",\"url\":\"https:\\\/\\\/bissafety.ca\\\/\",\"name\":\"BIS Safety Software\",\"description\":\"EHS Software for the Safety Professional\",\"publisher\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bissafety.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#organization\",\"name\":\"BIS Safety Software\",\"url\":\"https:\\\/\\\/bissafety.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bissafety.ca\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/BIS_Signature_ColourLogo_BlackFont.png.webp\",\"contentUrl\":\"https:\\\/\\\/bissafety.ca\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/BIS_Signature_ColourLogo_BlackFont.png.webp\",\"width\":2000,\"height\":412,\"caption\":\"BIS Safety Software\"},\"image\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BIS.Safety.Software\\\/\",\"https:\\\/\\\/x.com\\\/BISTraining\",\"https:\\\/\\\/www.instagram.com\\\/bis_safety_software\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bis-safety-software\\\/\",\"https:\\\/\\\/ca.pinterest.com\\\/bissafetysoftwarecanada\\\/\",\"https:\\\/\\\/gab.com\\\/bissafetysoftwarecanada\",\"https:\\\/\\\/www.youtube.com\\\/@BIS-SafetySoftware\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#\\\/schema\\\/person\\\/458bd937cef8ad403bf31aea9501f264\",\"name\":\"Nishant\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/908eb1c1db6efca8d8cdd37342584c2f4d239c256c80565d44536886c8a0c57e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/908eb1c1db6efca8d8cdd37342584c2f4d239c256c80565d44536886c8a0c57e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/908eb1c1db6efca8d8cdd37342584c2f4d239c256c80565d44536886c8a0c57e?s=96&d=mm&r=g\",\"caption\":\"Nishant\"},\"url\":\"https:\\\/\\\/bissafety.ca\\\/fr\\\/author\\\/nishantgraycell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Graham Jackson on Safety Leadership and Losing Your Ego","description":"From workplace injury to safety leadership, Graham Jackson transformed SkyFire Energy's safety culture with trust, humility, and experience.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bissafety.ca\/fr\/graham-jackson-wants-you-to-lose-your-ego\/","og_locale":"fr_CA","og_type":"article","og_title":"Graham Jackson Wants You to Lose Your Ego\u00a0","og_description":"From workplace injury to safety leadership, Graham Jackson transformed SkyFire Energy's safety culture with trust, humility, and experience.","og_url":"https:\/\/bissafety.ca\/fr\/graham-jackson-wants-you-to-lose-your-ego\/","og_site_name":"BIS Safety Software Canada","article_publisher":"https:\/\/www.facebook.com\/BIS.Safety.Software\/","article_published_time":"2026-07-17T07:17:01+00:00","article_modified_time":"2026-07-28T14:32:12+00:00","og_image":[{"width":721,"height":458,"url":"https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/Spotlights_PreviewCards_Graham.webp","type":"image\/webp"}],"author":"Nishant","twitter_card":"summary_large_image","twitter_creator":"@BISTraining","twitter_site":"@BISTraining","twitter_misc":{"\u00c9crit par":"Nishant","Estimation du temps de lecture":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bissafety.ca\/graham-jackson-wants-you-to-lose-your-ego\/#article","isPartOf":{"@id":"https:\/\/bissafety.ca\/graham-jackson-wants-you-to-lose-your-ego\/"},"author":{"name":"Nishant","@id":"https:\/\/bissafety.ca\/#\/schema\/person\/458bd937cef8ad403bf31aea9501f264"},"headline":"Graham Jackson Wants You to Lose Your Ego\u00a0","datePublished":"2026-07-17T07:17:01+00:00","dateModified":"2026-07-28T14:32:12+00:00","mainEntityOfPage":{"@id":"https:\/\/bissafety.ca\/graham-jackson-wants-you-to-lose-your-ego\/"},"wordCount":982,"publisher":{"@id":"https:\/\/bissafety.ca\/#organization"},"image":{"@id":"https:\/\/bissafety.ca\/graham-jackson-wants-you-to-lose-your-ego\/#primaryimage"},"thumbnailUrl":"https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/Spotlights_PreviewCards_Graham.webp","keywords":["Alberta","construction safety","employee safety","Graham Jackson","Health and Safety Manager","Leadership","Occupational Health and Safety","risk management","safety culture","safety leadership","safety professionals","SkyFire Energy","Solar Industry","Workplace Injury","Workplace safety"],"articleSection":["Spotlight Article"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/bissafety.ca\/graham-jackson-wants-you-to-lose-your-ego\/","url":"https:\/\/bissafety.ca\/graham-jackson-wants-you-to-lose-your-ego\/","name":"Graham Jackson on Safety Leadership and Losing Your Ego","isPartOf":{"@id":"https:\/\/bissafety.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bissafety.ca\/graham-jackson-wants-you-to-lose-your-ego\/#primaryimage"},"image":{"@id":"https:\/\/bissafety.ca\/graham-jackson-wants-you-to-lose-your-ego\/#primaryimage"},"thumbnailUrl":"https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/Spotlights_PreviewCards_Graham.webp","datePublished":"2026-07-17T07:17:01+00:00","dateModified":"2026-07-28T14:32:12+00:00","description":"From workplace injury to safety leadership, Graham Jackson transformed SkyFire Energy's safety culture with trust, humility, and experience.","breadcrumb":{"@id":"https:\/\/bissafety.ca\/graham-jackson-wants-you-to-lose-your-ego\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bissafety.ca\/graham-jackson-wants-you-to-lose-your-ego\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/bissafety.ca\/graham-jackson-wants-you-to-lose-your-ego\/#primaryimage","url":"https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/Spotlights_PreviewCards_Graham.webp","contentUrl":"https:\/\/bissafety.ca\/wp-content\/uploads\/2026\/07\/Spotlights_PreviewCards_Graham.webp","width":721,"height":458,"caption":"Graham Jackson"},{"@type":"BreadcrumbList","@id":"https:\/\/bissafety.ca\/graham-jackson-wants-you-to-lose-your-ego\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bissafety.ca\/"},{"@type":"ListItem","position":2,"name":"Graham Jackson Wants You to Lose Your Ego\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/bissafety.ca\/#website","url":"https:\/\/bissafety.ca\/","name":"BIS Safety Software","description":"EHS Software for the Safety Professional","publisher":{"@id":"https:\/\/bissafety.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bissafety.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/bissafety.ca\/#organization","name":"BIS Safety Software","url":"https:\/\/bissafety.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/bissafety.ca\/#\/schema\/logo\/image\/","url":"https:\/\/bissafety.ca\/wp-content\/uploads\/2025\/02\/BIS_Signature_ColourLogo_BlackFont.png.webp","contentUrl":"https:\/\/bissafety.ca\/wp-content\/uploads\/2025\/02\/BIS_Signature_ColourLogo_BlackFont.png.webp","width":2000,"height":412,"caption":"BIS Safety Software"},"image":{"@id":"https:\/\/bissafety.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BIS.Safety.Software\/","https:\/\/x.com\/BISTraining","https:\/\/www.instagram.com\/bis_safety_software\/","https:\/\/www.linkedin.com\/company\/bis-safety-software\/","https:\/\/ca.pinterest.com\/bissafetysoftwarecanada\/","https:\/\/gab.com\/bissafetysoftwarecanada","https:\/\/www.youtube.com\/@BIS-SafetySoftware"]},{"@type":"Person","@id":"https:\/\/bissafety.ca\/#\/schema\/person\/458bd937cef8ad403bf31aea9501f264","name":"Nishant","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/908eb1c1db6efca8d8cdd37342584c2f4d239c256c80565d44536886c8a0c57e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/908eb1c1db6efca8d8cdd37342584c2f4d239c256c80565d44536886c8a0c57e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/908eb1c1db6efca8d8cdd37342584c2f4d239c256c80565d44536886c8a0c57e?s=96&d=mm&r=g","caption":"Nishant"},"url":"https:\/\/bissafety.ca\/fr\/author\/nishantgraycell\/"}]}},"_links":{"self":[{"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/posts\/64739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/comments?post=64739"}],"version-history":[{"count":100,"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/posts\/64739\/revisions"}],"predecessor-version":[{"id":64917,"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/posts\/64739\/revisions\/64917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/media\/64742"}],"wp:attachment":[{"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/media?parent=64739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/categories?post=64739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/tags?post=64739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}