{"id":43047,"date":"2025-04-11T13:09:08","date_gmt":"2025-04-11T13:09:08","guid":{"rendered":"https:\/\/bissafety.ca\/courses\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\/"},"modified":"2025-08-13T11:39:44","modified_gmt":"2025-08-13T11:39:44","slug":"horas-de-servicio-modulo-5-conceptos-basicos-de-eld","status":"publish","type":"courses","link":"https:\/\/bissafety.ca\/fr\/courses\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\/","title":{"rendered":"Horas de Servicio M\u00f3dulo 5: Conceptos b\u00e1sicos de ELD"},"content":{"rendered":"<div class=\"title-bar\"> <b> DESCRIPCI\u00d3N GENERAL DEL CURSO <\/b> <\/div>\n<p> <\/p>\n<p> El m\u00f3dulo de formaci\u00f3n &#8216;Horas de Servicio M\u00f3dulo 5: Conceptos b\u00e1sicos de ELD&#8217; proporciona las herramientas necesarias para que los conductores utilicen los ELD eficientemente, adem\u00e1s de familiarizarse con las categor\u00edas de conducci\u00f3n de transporte personal y movimiento de patio. El curso tiene como objetivo mejorar la comprensi\u00f3n de los conductores sobre su responsabilidad en la disminuci\u00f3n de eventos de conducci\u00f3n no asignados, la necesidad de editar el registro y la importancia de revisarlo antes de su env\u00edo. <\/p>\n<p style=\"text-align: left\"> Tras la finalizaci\u00f3n exitosa de este curso, los conductores ser\u00e1n capaces de: <\/p>\n<\/p>\n<ul>\n<li> Explicar cu\u00e1ndo se necesita que los conductores usen un ELD <\/li>\n<li> Identificar los cinco componentes clave que deben estar presentes en la cabina al registrar las horas con un ELD <\/li>\n<li> Describir estrategias para reducir el tiempo de conducci\u00f3n no asignado <\/li>\n<li> Comprender qu\u00e9 hacer cuando su ELD no funcione correctamente <\/li>\n<li> Diferenciar entre la coerci\u00f3n y el acoso <\/li>\n<\/ul>\n<p> <\/p>\n<div class=\"title-bar\"> <b> TEMAS DEL CURSO <\/b> <\/div>\n<p> <\/p>\n<p> El curso en l\u00ednea &#8216;Horas de Servicio M\u00f3dulo 5: Conceptos b\u00e1sicos de ELD&#8217; aborda los siguientes temas: <\/p>\n<ul>\n<li> Uso de ELD <\/li>\n<li> Expectativas del conductor con respecto a ELD <\/li>\n<li> Prevenci\u00f3n del acoso <\/li>\n<\/ul>\n<p> <\/p>\n<div class=\"title-bar\"> <b> DURACI\u00d3N DEL CURSO EN L\u00cdNEA <\/b> <\/div>\n<p> <\/p>\n<p> Duraci\u00f3n estimada de 20 minutos <\/p>\n<p> <\/p>\n<div class=\"title-bar\"> <b> MARCA DE PASO <br \/> <\/b> <\/div>\n<p> <\/p>\n<p> Las evaluaciones realizadas durante este curso en l\u00ednea est\u00e1n dise\u00f1adas para reforzar la informaci\u00f3n presentada. Se requiere obtener una calificaci\u00f3n del 80% para aprobar el curso. Se permite un m\u00e1ximo de tres intentos para alcanzar la calificaci\u00f3n de aprobado. Se proporcionan recursos descargables en forma de un manual completo del estudiante. Este manual sirve como un valioso recurso para futuras consultas y retenci\u00f3n de conocimientos. <\/p>\n<p> <\/p>\n<div class=\"title-bar\"> <b> CERTIFICAT DE FIN D&#x27;\u00c9TUDES <\/b> <\/div>\n<p> <\/p>\n<p> Tras la finalizaci\u00f3n exitosa de este curso en l\u00ednea, un certificado de finalizaci\u00f3n estar\u00e1 disponible para su descarga e impresi\u00f3n. <\/p>\n<p> <\/p>\n<div class=\"title-bar\"> <b> APER\u00c7U DU COURS <\/b> <\/div>\n<p> <\/p>","protected":false},"excerpt":{"rendered":"<p>El m\u00f3dulo de formaci\u00f3n &#8216;Horas de Servicio M\u00f3dulo 5: Conceptos b\u00e1sicos de ELD&#8217; se ha desarrollado para facilitar a los conductores el uso de los ELD de forma correcta, y para familiarizarse con las categor\u00edas de conducci\u00f3n de transporte personal y movimiento de patio.<\/p>","protected":false},"featured_media":43048,"template":"","meta":{"_acf_changed":false,"content-type":""},"course-category":[325,326,330],"class_list":["post-43047","courses","type-courses","status-publish","has-post-thumbnail","hentry","course-category-awareness","course-category-driver","course-category-safety"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Horas de Servicio M\u00f3dulo 5: Conceptos b\u00e1sicos de ELD<\/title>\n<meta name=\"description\" content=\"Aprende los conceptos b\u00e1sicos de ELD en el M\u00f3dulo 5 de Horas de Servicio. Mejora el cumplimiento y la gesti\u00f3n de registros para una operaci\u00f3n eficiente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bissafety.ca\/fr\/courses\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Horas de Servicio M\u00f3dulo 5: Conceptos b\u00e1sicos de ELD\" \/>\n<meta property=\"og:description\" content=\"Aprende los conceptos b\u00e1sicos de ELD en el M\u00f3dulo 5 de Horas de Servicio. Mejora el cumplimiento y la gesti\u00f3n de registros para una operaci\u00f3n eficiente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bissafety.ca\/fr\/courses\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\/\" \/>\n<meta property=\"og:site_name\" content=\"BIS Safety Software Canada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BIS.Safety.Software\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-13T11:39:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bissafety.ca\/wp-content\/uploads\/2025\/04\/FE40BA4A1991CCC928CCFE6953062C42.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BISTraining\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/courses\\\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\\\/\",\"url\":\"https:\\\/\\\/bissafety.ca\\\/courses\\\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\\\/\",\"name\":\"Horas de Servicio M\u00f3dulo 5: Conceptos b\u00e1sicos de ELD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/courses\\\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/courses\\\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bissafety.ca\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/FE40BA4A1991CCC928CCFE6953062C42.jpeg\",\"datePublished\":\"2025-04-11T13:09:08+00:00\",\"dateModified\":\"2025-08-13T11:39:44+00:00\",\"description\":\"Aprende los conceptos b\u00e1sicos de ELD en el M\u00f3dulo 5 de Horas de Servicio. Mejora el cumplimiento y la gesti\u00f3n de registros para una operaci\u00f3n eficiente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/courses\\\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bissafety.ca\\\/courses\\\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/courses\\\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bissafety.ca\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/FE40BA4A1991CCC928CCFE6953062C42.jpeg\",\"contentUrl\":\"https:\\\/\\\/bissafety.ca\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/FE40BA4A1991CCC928CCFE6953062C42.jpeg\",\"width\":1920,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/courses\\\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bissafety.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Courses\",\"item\":\"https:\\\/\\\/bissafety.ca\\\/fr\\\/courses\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Horas de Servicio M\u00f3dulo 5: Conceptos b\u00e1sicos de ELD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#website\",\"url\":\"https:\\\/\\\/bissafety.ca\\\/\",\"name\":\"BIS Safety Software\",\"description\":\"EHS Software for the Safety Professional\",\"publisher\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bissafety.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#organization\",\"name\":\"BIS Safety Software\",\"url\":\"https:\\\/\\\/bissafety.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bissafety.ca\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/BIS_Signature_ColourLogo_BlackFont.png.webp\",\"contentUrl\":\"https:\\\/\\\/bissafety.ca\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/BIS_Signature_ColourLogo_BlackFont.png.webp\",\"width\":2000,\"height\":412,\"caption\":\"BIS Safety Software\"},\"image\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BIS.Safety.Software\\\/\",\"https:\\\/\\\/x.com\\\/BISTraining\",\"https:\\\/\\\/www.instagram.com\\\/bis_safety_software\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bis-safety-software\\\/\",\"https:\\\/\\\/ca.pinterest.com\\\/bissafetysoftwarecanada\\\/\",\"https:\\\/\\\/gab.com\\\/bissafetysoftwarecanada\",\"https:\\\/\\\/www.youtube.com\\\/@BIS-SafetySoftware\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Horas de Servicio M\u00f3dulo 5: Conceptos b\u00e1sicos de ELD","description":"Aprende los conceptos b\u00e1sicos de ELD en el M\u00f3dulo 5 de Horas de Servicio. Mejora el cumplimiento y la gesti\u00f3n de registros para una operaci\u00f3n eficiente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bissafety.ca\/fr\/courses\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\/","og_locale":"fr_CA","og_type":"article","og_title":"Horas de Servicio M\u00f3dulo 5: Conceptos b\u00e1sicos de ELD","og_description":"Aprende los conceptos b\u00e1sicos de ELD en el M\u00f3dulo 5 de Horas de Servicio. Mejora el cumplimiento y la gesti\u00f3n de registros para una operaci\u00f3n eficiente.","og_url":"https:\/\/bissafety.ca\/fr\/courses\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\/","og_site_name":"BIS Safety Software Canada","article_publisher":"https:\/\/www.facebook.com\/BIS.Safety.Software\/","article_modified_time":"2025-08-13T11:39:44+00:00","og_image":[{"width":1920,"height":320,"url":"https:\/\/bissafety.ca\/wp-content\/uploads\/2025\/04\/FE40BA4A1991CCC928CCFE6953062C42.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@BISTraining","twitter_misc":{"Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bissafety.ca\/courses\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\/","url":"https:\/\/bissafety.ca\/courses\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\/","name":"Horas de Servicio M\u00f3dulo 5: Conceptos b\u00e1sicos de ELD","isPartOf":{"@id":"https:\/\/bissafety.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bissafety.ca\/courses\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\/#primaryimage"},"image":{"@id":"https:\/\/bissafety.ca\/courses\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\/#primaryimage"},"thumbnailUrl":"https:\/\/bissafety.ca\/wp-content\/uploads\/2025\/04\/FE40BA4A1991CCC928CCFE6953062C42.jpeg","datePublished":"2025-04-11T13:09:08+00:00","dateModified":"2025-08-13T11:39:44+00:00","description":"Aprende los conceptos b\u00e1sicos de ELD en el M\u00f3dulo 5 de Horas de Servicio. Mejora el cumplimiento y la gesti\u00f3n de registros para una operaci\u00f3n eficiente.","breadcrumb":{"@id":"https:\/\/bissafety.ca\/courses\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bissafety.ca\/courses\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/bissafety.ca\/courses\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\/#primaryimage","url":"https:\/\/bissafety.ca\/wp-content\/uploads\/2025\/04\/FE40BA4A1991CCC928CCFE6953062C42.jpeg","contentUrl":"https:\/\/bissafety.ca\/wp-content\/uploads\/2025\/04\/FE40BA4A1991CCC928CCFE6953062C42.jpeg","width":1920,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/bissafety.ca\/courses\/horas-de-servicio-modulo-5-conceptos-basicos-de-eld\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bissafety.ca\/"},{"@type":"ListItem","position":2,"name":"Courses","item":"https:\/\/bissafety.ca\/fr\/courses\/"},{"@type":"ListItem","position":3,"name":"Horas de Servicio M\u00f3dulo 5: Conceptos b\u00e1sicos de ELD"}]},{"@type":"WebSite","@id":"https:\/\/bissafety.ca\/#website","url":"https:\/\/bissafety.ca\/","name":"BIS Safety Software","description":"EHS Software for the Safety Professional","publisher":{"@id":"https:\/\/bissafety.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bissafety.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/bissafety.ca\/#organization","name":"BIS Safety Software","url":"https:\/\/bissafety.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/bissafety.ca\/#\/schema\/logo\/image\/","url":"https:\/\/bissafety.ca\/wp-content\/uploads\/2025\/02\/BIS_Signature_ColourLogo_BlackFont.png.webp","contentUrl":"https:\/\/bissafety.ca\/wp-content\/uploads\/2025\/02\/BIS_Signature_ColourLogo_BlackFont.png.webp","width":2000,"height":412,"caption":"BIS Safety Software"},"image":{"@id":"https:\/\/bissafety.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BIS.Safety.Software\/","https:\/\/x.com\/BISTraining","https:\/\/www.instagram.com\/bis_safety_software\/","https:\/\/www.linkedin.com\/company\/bis-safety-software\/","https:\/\/ca.pinterest.com\/bissafetysoftwarecanada\/","https:\/\/gab.com\/bissafetysoftwarecanada","https:\/\/www.youtube.com\/@BIS-SafetySoftware"]}]}},"_links":{"self":[{"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/courses\/43047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/courses"}],"about":[{"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/types\/courses"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/media\/43048"}],"wp:attachment":[{"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/media?parent=43047"}],"wp:term":[{"taxonomy":"course-category","embeddable":true,"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/course-category?post=43047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}