{"id":35113,"date":"2025-03-26T10:01:29","date_gmt":"2025-03-26T10:01:29","guid":{"rendered":"https:\/\/bissafety.ca\/courses\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\/"},"modified":"2025-08-13T07:55:47","modified_gmt":"2025-08-13T07:55:47","slug":"transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis","status":"publish","type":"courses","link":"https:\/\/bissafety.ca\/fr\/courses\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\/","title":{"rendered":"Transport de marchandises dangereuses \u2013 Transfrontalier \u2013 du Canada vers les \u00c9tats-Unis"},"content":{"rendered":"<div class=\"title-bar\" style=\"font-size: 18.0px\"><b><b>APER\u00c7U DU MODULE EN LIGNE<\/b><\/b><\/div>\n<p style=\"font-size: 14.0px\"><\/p>\n<p style=\"font-size: 14.0px\">Ce module de formation est con\u00e7u pour les exp\u00e9diteurs de marchandises dangereuses par voie terrestre du Canada vers les \u00c9tats-Unis, en vertu des dispositions actuelles de r\u00e9ciprocit\u00e9 du r\u00e8glement sur les marchandises dangereuses du 49 CFR. Le programme met l&#8217;accent sur les responsabilit\u00e9s g\u00e9n\u00e9rales de l&#8217;exp\u00e9diteur.<\/p>\n<p style=\"font-size: 14.0px\"><strong><b>LES EXP\u00c9DITEURS DE MARCHANDISES DANGEREUSES SONT REQUIS POUR SUIVRE CETTE FORMATION SELON LES R\u00c8GLES DE L&#8217;IATA.<\/b><\/strong><\/p>\n<p style=\"font-size: 14.0px\"><strong><b><br \/><\/b><\/strong><\/p>\n<div class=\"title-bar\" style=\"font-size: 18.0px\"><strong><b><b>CONTENU DU MODULE<\/b><\/b><\/strong><\/div>\n<div><\/p>\n<ul style=\"font-size: 14.0px\">\n<li>Introduction<\/li>\n<li>Classification et Identification des marchandises dangereuses<\/li>\n<li>Exigences pour l\u2019emballage<\/li>\n<li>Marquage et \u00e9tiquetage<\/li>\n<li>Documentation<\/li>\n<li>Plaques, S\u00e9gr\u00e9gation et Rapports<\/li>\n<li>Exemptions<\/li>\n<li>Quiz<\/li>\n<\/ul>\n<p><\/p>\n<div class=\"title-bar\" style=\"font-size: 18.0px\"><b><b>DUR\u00c9E DU MODULE EN LIGNE<\/b><\/b><\/div>\n<\/div>\n<p style=\"font-size: 14.0px\"><\/p>\n<p style=\"font-size: 14.0px\">Environ 90 minutes<\/p>\n<p style=\"font-size: 14.0px\"><\/p>\n<div class=\"title-bar\" style=\"font-size: 18.0px\"><b><b><b>\u00c9VALUATION<\/b><\/b><\/b><\/div>\n<p style=\"font-size: 14.0px\"><span><br \/><\/span><\/p>\n<p style=\"font-size: 14.0px\"><span>Des tests sont r\u00e9alis\u00e9s tout au long du cours Transport de marchandises dangereuses \u2013 Transfrontalier \u2013 du Canada vers les \u00c9tats-Unis pour renforcer les connaissances acquises. Un score de 80% est n\u00e9cessaire pour obtenir un certificat de r\u00e9ussite. Les participants peuvent reprendre le module quatre fois si le score de r\u00e9ussite n&#8217;est pas atteint.<\/span><\/p>\n<p style=\"font-size: 14.0px\"><\/p>\n<p style=\"font-size: 14.0px\">\n<div style=\"font-size: 14.0px\">\n<div class=\"title-bar\" style=\"font-size: 18.0px\"><b><b>CERTIFICAT DE R\u00c9USSITE<\/b><\/b><\/div>\n<\/div>\n<p style=\"font-size: 14.0px\"><\/p>\n<p style=\"font-size: 14.0px\">\u00c0 la fin du cours en ligne, un certificat de r\u00e9ussite est disponible pour t\u00e9l\u00e9chargement et impression.<\/p>\n<p style=\"font-size: 14.0px\"><b><b>Pour les achats de groupe, veuillez nous contacter directement.<\/b><\/b><\/p>\n<p style=\"font-size: 14.0px\"><b><b><br \/><\/b><\/b><\/p>\n<div class=\"title-bar\" style=\"font-size: 18.0px\"><b><b><b><b><b><b><b>PR\u00c9SENTATION DU MODULE<\/b><\/b><\/b><\/b><\/b><\/b><\/b><\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WB-CLR15ER Ce cours est sp\u00e9cialement \u00e9labor\u00e9 pour ceux qui sont responsables de l&#8217;exp\u00e9dition de marchandises dangereuses par route du Canada vers les \u00c9tats-Unis, conform\u00e9ment aux dispositions actuelles de r\u00e9ciprocit\u00e9 du r\u00e8glement 49 CFR sur le transport de marchandises dangereuses. Une r\u00e9vision approfondie des responsabilit\u00e9s de l&#8217;exp\u00e9diteur est int\u00e9gr\u00e9e dans le cours.<\/p>","protected":false},"featured_media":35114,"template":"","meta":{"_acf_changed":false,"content-type":""},"course-category":[330],"class_list":["post-35113","courses","type-courses","status-publish","has-post-thumbnail","hentry","course-category-safety"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Transport de marchandises dangereuses \u2013 Transfrontalier<\/title>\n<meta name=\"description\" content=\"Ce cours traite du transport s\u00e9curitaire de marchandises dangereuses du Canada vers les \u00c9tats-Unis, en couvrant la conformit\u00e9, la documentation et les protocoles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bissafety.ca\/fr\/courses\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transport de marchandises dangereuses \u2013 Transfrontalier \u2013 du Canada vers les \u00c9tats-Unis\" \/>\n<meta property=\"og:description\" content=\"Ce cours traite du transport s\u00e9curitaire de marchandises dangereuses du Canada vers les \u00c9tats-Unis, en couvrant la conformit\u00e9, la documentation et les protocoles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bissafety.ca\/fr\/courses\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\/\" \/>\n<meta property=\"og:site_name\" content=\"BIS Safety Software Canada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BIS.Safety.Software\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-13T07:55:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bissafety.ca\/wp-content\/uploads\/2025\/03\/EB5BAF1D47227AB1995F0B584808E856.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BISTraining\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/courses\\\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\\\/\",\"url\":\"https:\\\/\\\/bissafety.ca\\\/courses\\\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\\\/\",\"name\":\"Transport de marchandises dangereuses \u2013 Transfrontalier\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/courses\\\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/courses\\\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bissafety.ca\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/EB5BAF1D47227AB1995F0B584808E856.jpg\",\"datePublished\":\"2025-03-26T10:01:29+00:00\",\"dateModified\":\"2025-08-13T07:55:47+00:00\",\"description\":\"Ce cours traite du transport s\u00e9curitaire de marchandises dangereuses du Canada vers les \u00c9tats-Unis, en couvrant la conformit\u00e9, la documentation et les protocoles.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/courses\\\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bissafety.ca\\\/courses\\\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/courses\\\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bissafety.ca\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/EB5BAF1D47227AB1995F0B584808E856.jpg\",\"contentUrl\":\"https:\\\/\\\/bissafety.ca\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/EB5BAF1D47227AB1995F0B584808E856.jpg\",\"width\":1920,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/courses\\\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bissafety.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Courses\",\"item\":\"https:\\\/\\\/bissafety.ca\\\/courses\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Transport de marchandises dangereuses \u2013 Transfrontalier \u2013 du Canada vers les \u00c9tats-Unis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#website\",\"url\":\"https:\\\/\\\/bissafety.ca\\\/\",\"name\":\"BIS Safety Software\",\"description\":\"EHS Software for the Safety Professional\",\"publisher\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bissafety.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#organization\",\"name\":\"BIS Safety Software\",\"url\":\"https:\\\/\\\/bissafety.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bissafety.ca\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/BIS_Signature_ColourLogo_BlackFont.png.webp\",\"contentUrl\":\"https:\\\/\\\/bissafety.ca\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/BIS_Signature_ColourLogo_BlackFont.png.webp\",\"width\":2000,\"height\":412,\"caption\":\"BIS Safety Software\"},\"image\":{\"@id\":\"https:\\\/\\\/bissafety.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BIS.Safety.Software\\\/\",\"https:\\\/\\\/x.com\\\/BISTraining\",\"https:\\\/\\\/www.instagram.com\\\/bis_safety_software\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bis-safety-software\\\/\",\"https:\\\/\\\/ca.pinterest.com\\\/bissafetysoftwarecanada\\\/\",\"https:\\\/\\\/gab.com\\\/bissafetysoftwarecanada\",\"https:\\\/\\\/www.youtube.com\\\/@BIS-SafetySoftware\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transport de marchandises dangereuses \u2013 Transfrontalier","description":"Ce cours traite du transport s\u00e9curitaire de marchandises dangereuses du Canada vers les \u00c9tats-Unis, en couvrant la conformit\u00e9, la documentation et les protocoles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bissafety.ca\/fr\/courses\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\/","og_locale":"fr_CA","og_type":"article","og_title":"Transport de marchandises dangereuses \u2013 Transfrontalier \u2013 du Canada vers les \u00c9tats-Unis","og_description":"Ce cours traite du transport s\u00e9curitaire de marchandises dangereuses du Canada vers les \u00c9tats-Unis, en couvrant la conformit\u00e9, la documentation et les protocoles.","og_url":"https:\/\/bissafety.ca\/fr\/courses\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\/","og_site_name":"BIS Safety Software Canada","article_publisher":"https:\/\/www.facebook.com\/BIS.Safety.Software\/","article_modified_time":"2025-08-13T07:55:47+00:00","og_image":[{"width":1920,"height":320,"url":"https:\/\/bissafety.ca\/wp-content\/uploads\/2025\/03\/EB5BAF1D47227AB1995F0B584808E856.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@BISTraining","twitter_misc":{"Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bissafety.ca\/courses\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\/","url":"https:\/\/bissafety.ca\/courses\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\/","name":"Transport de marchandises dangereuses \u2013 Transfrontalier","isPartOf":{"@id":"https:\/\/bissafety.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bissafety.ca\/courses\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\/#primaryimage"},"image":{"@id":"https:\/\/bissafety.ca\/courses\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\/#primaryimage"},"thumbnailUrl":"https:\/\/bissafety.ca\/wp-content\/uploads\/2025\/03\/EB5BAF1D47227AB1995F0B584808E856.jpg","datePublished":"2025-03-26T10:01:29+00:00","dateModified":"2025-08-13T07:55:47+00:00","description":"Ce cours traite du transport s\u00e9curitaire de marchandises dangereuses du Canada vers les \u00c9tats-Unis, en couvrant la conformit\u00e9, la documentation et les protocoles.","breadcrumb":{"@id":"https:\/\/bissafety.ca\/courses\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bissafety.ca\/courses\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/bissafety.ca\/courses\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\/#primaryimage","url":"https:\/\/bissafety.ca\/wp-content\/uploads\/2025\/03\/EB5BAF1D47227AB1995F0B584808E856.jpg","contentUrl":"https:\/\/bissafety.ca\/wp-content\/uploads\/2025\/03\/EB5BAF1D47227AB1995F0B584808E856.jpg","width":1920,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/bissafety.ca\/courses\/transport-de-marchandises-dangereuses-transfrontalier-du-canada-vers-les-etats-unis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bissafety.ca\/"},{"@type":"ListItem","position":2,"name":"Courses","item":"https:\/\/bissafety.ca\/courses\/"},{"@type":"ListItem","position":3,"name":"Transport de marchandises dangereuses \u2013 Transfrontalier \u2013 du Canada vers les \u00c9tats-Unis"}]},{"@type":"WebSite","@id":"https:\/\/bissafety.ca\/#website","url":"https:\/\/bissafety.ca\/","name":"Logiciel de s\u00e9curit\u00e9 BIS","description":"EHS Software for the Safety Professional","publisher":{"@id":"https:\/\/bissafety.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bissafety.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/bissafety.ca\/#organization","name":"Logiciel de s\u00e9curit\u00e9 BIS","url":"https:\/\/bissafety.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/bissafety.ca\/#\/schema\/logo\/image\/","url":"https:\/\/bissafety.ca\/wp-content\/uploads\/2025\/02\/BIS_Signature_ColourLogo_BlackFont.png.webp","contentUrl":"https:\/\/bissafety.ca\/wp-content\/uploads\/2025\/02\/BIS_Signature_ColourLogo_BlackFont.png.webp","width":2000,"height":412,"caption":"BIS Safety Software"},"image":{"@id":"https:\/\/bissafety.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BIS.Safety.Software\/","https:\/\/x.com\/BISTraining","https:\/\/www.instagram.com\/bis_safety_software\/","https:\/\/www.linkedin.com\/company\/bis-safety-software\/","https:\/\/ca.pinterest.com\/bissafetysoftwarecanada\/","https:\/\/gab.com\/bissafetysoftwarecanada","https:\/\/www.youtube.com\/@BIS-SafetySoftware"]}]}},"_links":{"self":[{"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/courses\/35113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/courses"}],"about":[{"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/types\/courses"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/media\/35114"}],"wp:attachment":[{"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/media?parent=35113"}],"wp:term":[{"taxonomy":"course-category","embeddable":true,"href":"https:\/\/bissafety.ca\/fr\/wp-json\/wp\/v2\/course-category?post=35113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}